{"id":13001,"date":"2026-05-05T19:15:32","date_gmt":"2026-05-05T22:15:32","guid":{"rendered":"https:\/\/www.ucse.edu.ar\/notiucse\/?p=13001"},"modified":"2026-05-28T20:54:29","modified_gmt":"2026-05-28T23:54:29","slug":"abordaje-de-la-fibrosis-quimica-en-una-clase-especializada-para-estudiantes-de-kinesiologia","status":"publish","type":"post","link":"https:\/\/www.ucse.edu.ar\/notiucse\/2026\/05\/05\/abordaje-de-la-fibrosis-quimica-en-una-clase-especializada-para-estudiantes-de-kinesiologia\/","title":{"rendered":"Abordaje de la fibrosis qu\u00edstica en una clase especializada para estudiantes de Kinesiolog\u00eda"},"content":{"rendered":"\n<p>El pasado jueves 30 de abril, estudiantes de cuarto a\u00f1o de la <strong>Licenciatura en Kinesiolog\u00eda y Fisiatr\u00eda<\/strong> participaron de una clase especial organizada por la c\u00e1tedra de la Dra. Mar\u00eda Garnica y la licenciada Ximena Contreras. La actividad titulada \u201c<strong>Fibrosis Qu\u00edstica, un abordaje Fisiokin\u00e9sico<\/strong>\u201d, tuvo como objetivos profundizar en el tratamiento integral de esta patolog\u00eda desde la perspectiva profesional.<\/p>\n\n\n\n<p>Durante el encuentro, se desarrollaron contenidos vinculados al <strong>diagn\u00f3stico<\/strong>, el <strong>tratamiento <\/strong>y especialmente, al <strong>rol del kinesi\u00f3logo<\/strong> en el acompa\u00f1amiento de los pacientes con <strong>fibrosis qu\u00edstica<\/strong>. La propuesta acad\u00e9mica busc\u00f3 no solo reforzar conocimientos te\u00f3ricos, sino tambi\u00e9n brindar herramientas pr\u00e1cticas que resultan fundamentales para el futuro desempe\u00f1o profesional de los estudiantes.<\/p>\n\n\n\n<p>La clase estuvo a cargo de la licenciada en Kinesiolog\u00eda y Fisioterapia <strong>Alejandra Ya\u00f1ez Moreno<\/strong>, que abord\u00f3 la tem\u00e1tica de manera integral y din\u00e1mica. A lo largo de la jornada los alumnos tuvieron la oportunidad de realizar consultas, plantear inquietudes\u00a0 y participar activamente en un intercambio que enriqueci\u00f3 la experiencia formativa.<\/p>\n\n\n\n<p>Este tipo de iniciativa refuerza la importancia de la <strong>formaci\u00f3n <\/strong>continua y del contacto directo con <strong>profesionales <\/strong>en ejercicio, permitiendo a los estudiantes ampliar su mirada sobre el abordaje interdisciplinario en el campo de la salud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fue una clase especializada para alumnos de cuarto a\u00f1o de Kinesiolog\u00eda y Fisiatr\u00eda, donde se abord\u00f3 el rol clave del kinesi\u00f3logo en el acompa\u00f1amiento de los pacientes.<\/p>\n","protected":false},"author":6,"featured_media":13002,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[9,72],"tags":[52,132],"_links":{"self":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts\/13001"}],"collection":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/comments?post=13001"}],"version-history":[{"count":6,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts\/13001\/revisions"}],"predecessor-version":[{"id":13220,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts\/13001\/revisions\/13220"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/media\/13002"}],"wp:attachment":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/media?parent=13001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/categories?post=13001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/tags?post=13001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}