{"id":13054,"date":"2026-05-12T19:10:31","date_gmt":"2026-05-12T22:10:31","guid":{"rendered":"https:\/\/www.ucse.edu.ar\/notiucse\/?p=13054"},"modified":"2026-05-12T19:10:32","modified_gmt":"2026-05-12T22:10:32","slug":"el-lic-andres-davicino-brindo-una-charla-en-la-expo-feld-y-1-congreso-de-alto-rendimiento","status":"publish","type":"post","link":"https:\/\/www.ucse.edu.ar\/notiucse\/2026\/05\/12\/el-lic-andres-davicino-brindo-una-charla-en-la-expo-feld-y-1-congreso-de-alto-rendimiento\/","title":{"rendered":"El Lic. Andr\u00e9s Davicino brind\u00f3 una charla en la Expo FELD y 1\u00b0 Congreso de Alto Rendimiento"},"content":{"rendered":"\n<p>Los d\u00edas 8 y 9 de mayo se desarroll\u00f3 en el Nodo Tecnol\u00f3gico la <strong>Expo FELD y el 1\u00b0 Congreso de Alto Rendimiento<\/strong>, un espacio que reuni\u00f3 a profesionales, especialistas y disertantes de todo el pa\u00eds para reflexionar e intercambiar conocimientos acerca del <strong>deporte<\/strong>, la <strong>ciencia aplicada<\/strong>, la <strong>tecnolog\u00eda <\/strong>y la <strong>gesti\u00f3n vinculados al alto rendimiento<\/strong>.<\/p>\n\n\n\n<p>En este marco, el <strong>Lic. Andr\u00e9s Davicino<\/strong>, docente de la carrera de <strong>Kinesiolog\u00eda <\/strong>de la Universidad Cat\u00f3lica de Santiago del Estero, particip\u00f3 como expositor de la charla \u201c<strong>Clasificaci\u00f3n Funcional, deporte y salud<\/strong>\u201d, donde abord\u00f3 conceptos relacionados con la evaluaci\u00f3n y la clasificaci\u00f3n de personas con discapacidad dentro del \u00e1mbito deportivo. Durante la presentaci\u00f3n, Davicino destac\u00f3 la importancia de estos procesos para garantizar la <strong>inclusi\u00f3n<\/strong>, la <strong>equidad <\/strong>y la <strong>participaci\u00f3n segura <\/strong>de los deportistas en distintas disciplinas, promoviendo una mirada integral sobre el deporte adaptado y la salud.<\/p>\n\n\n\n<p>Asimismo, en el encuentro se desarrollaron contenidos vinculados a los criterios de <strong>clasificaci\u00f3n funcional<\/strong>, el <strong>trabajo interdisciplinario<\/strong> entre los profesionales de la salud y la educaci\u00f3n f\u00edsica, y las herramientas necesarias para fortalecer <strong>pr\u00e1cticas deportivas adaptadas<\/strong> desde una perspectiva inclusiva.<\/p>\n\n\n\n<p>La participaci\u00f3n de la <strong>UCSE <\/strong>en este <strong>Congreso <\/strong>permiti\u00f3 generar un valioso espacio de intercambio y actualizaci\u00f3n profesional, contribuyendo al fortalecimiento del conocimiento y reafirmando el compromiso con la promoci\u00f3n de un deporte m\u00e1s accesible e inclusivo para toda la comunidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Explo FELD y el 1\u00b0 Congreso de Alto Rendimiento reunieron en el Nodo a especialistas de todo el pa\u00eds para debatir sobre deporte, ciencia y salud. En representaci\u00f3n de la UCSE, el Lic. Andres Davicino particip\u00f3 con una exposici\u00f3n sobre clasificaci\u00f3n funcional, integraci\u00f3n y deporte adaptado.  <\/p>\n","protected":false},"author":6,"featured_media":13057,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[9],"tags":[232,132],"_links":{"self":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts\/13054"}],"collection":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/comments?post=13054"}],"version-history":[{"count":2,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts\/13054\/revisions"}],"predecessor-version":[{"id":13058,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts\/13054\/revisions\/13058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/media\/13057"}],"wp:attachment":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/media?parent=13054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/categories?post=13054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/tags?post=13054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}