{"id":13132,"date":"2026-05-21T01:53:32","date_gmt":"2026-05-21T04:53:32","guid":{"rendered":"https:\/\/www.ucse.edu.ar\/notiucse\/?p=13132"},"modified":"2026-05-21T01:53:34","modified_gmt":"2026-05-21T04:53:34","slug":"alejandro-piscitelli-y-juan-pablo-salomon-disertaran-sobre-trabajo-y-educacion-en-la-era-de-la-ia","status":"publish","type":"post","link":"https:\/\/www.ucse.edu.ar\/notiucse\/2026\/05\/21\/alejandro-piscitelli-y-juan-pablo-salomon-disertaran-sobre-trabajo-y-educacion-en-la-era-de-la-ia\/","title":{"rendered":"Alejandro Piscitelli y Juan Pablo Salom\u00f3n disertar\u00e1n sobre Trabajo y Educaci\u00f3n en la era de la IA"},"content":{"rendered":"\n<p>La segunda jornada de la <strong>Smart City 2026 Expo Santiago del Estero<\/strong> ser\u00e1 escenario de la charla <strong>\u201cTrabajo y Educaci\u00f3n en la era de la IA\u201d<\/strong>, a cargo del especialista invitado de la Facultad de Ciencias Pol\u00edticas, Sociales y Jur\u00eddicas, <strong>Alejandro Piscitelli<\/strong>; y de <strong>Juan Pablo Salom\u00f3n<\/strong>, Director del Observatorio de Inteligencia Artificial de la UCSE y Prosecretario de Extensi\u00f3n de FCPSyJ. La actividad se realizar\u00e1 el jueves 21 de mayo a partir de las <strong>11:00<\/strong> en la <strong>Sala 1 Juan Francisco Borges<\/strong> del Centro de Convenciones FORUM.<\/p>\n\n\n\n<p>En primera instancia, Piscitelli abordar\u00e1 <strong>\u201cEl perfil trabajador del futuro. El trabajo y la educaci\u00f3n en la era de la Inteligencia Artificial\u201d<\/strong>, donde Salom\u00f3n actuar\u00e1 de moderador de la charla teniendo una modalidad de entrevista dialogada, para luego referirse a los <strong>\u201cDesaf\u00edos para los estudios del mercado de Trabajo de Santiago del Estero en la era digital\u201d.\u00a0<\/strong><\/p>\n\n\n\n<p>El encuentro tiene por objetivo analizar c\u00f3mo las herramientas de IA est\u00e1n reconfigurando los perfiles profesionales, y es una de las actividades que la UCSE y la UNSE presentaron en su cronograma para Smart City 2026.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enmarcada en Smart City 2026, la disertaci\u00f3n tendr\u00e1 lugar este jueves a las 11:00, y buscar\u00e1 analizar el impacto de la inteligencia artificial en las profesiones.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[73],"tags":[233],"_links":{"self":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts\/13132"}],"collection":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/comments?post=13132"}],"version-history":[{"count":1,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts\/13132\/revisions"}],"predecessor-version":[{"id":13134,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts\/13132\/revisions\/13134"}],"wp:attachment":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/media?parent=13132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/categories?post=13132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/tags?post=13132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}