{"id":13239,"date":"2026-06-02T19:29:40","date_gmt":"2026-06-02T22:29:40","guid":{"rendered":"https:\/\/www.ucse.edu.ar\/notiucse\/?p=13239"},"modified":"2026-06-02T20:59:34","modified_gmt":"2026-06-02T23:59:34","slug":"estudiantes-de-produccion-agroecologica-y-organica-realizaron-practicas-de-manejo-caprino-en-el-campo-experimental-de-inta","status":"publish","type":"post","link":"https:\/\/www.ucse.edu.ar\/notiucse\/2026\/06\/02\/estudiantes-de-produccion-agroecologica-y-organica-realizaron-practicas-de-manejo-caprino-en-el-campo-experimental-de-inta\/","title":{"rendered":"Estudiantes de Producci\u00f3n Agroecol\u00f3gica y Org\u00e1nica\u00a0realizaron pr\u00e1cticas de manejo caprino en el campo experimental de INTA\u00a0"},"content":{"rendered":"\n<p>Alumnos de tercer a\u00f1o de la <strong>Tecnicatura Universitaria en Producci\u00f3n Agroecol\u00f3gica y Org\u00e1nica<\/strong> participaron el pasado 1 de junio de una jornada de pr\u00e1cticas a campo en las instalaciones del <strong>campo experimental<\/strong> del <strong>Instituto Nacional de Tecnolog\u00eda Agropecuaria<\/strong> (INTA), donde profundizaron conocimientos vinculados al <strong>manejo caprino<\/strong> y la gesti\u00f3n sustentable de los recursos productivos.<\/p>\n\n\n\n<p>La actividad tuvo como objetivo fortalecer los contenidos te\u00f3ricos abordados en el aula mediante experiencias directas en el territorio. Durante la jornada, los estudiantes aplicaron herramientas de precisi\u00f3n para la toma de decisiones en tiempo real relacionadas con la <strong>nutrici\u00f3n adicional<\/strong> y el <strong>manejo del pastoreo<\/strong>.<\/p>\n\n\n\n<p>Entre las principales tareas desarrolladas, trabajaron con <strong>indicadores de nutrici\u00f3n animal<\/strong>, una herramienta fundamental para evaluar individualmente el estado de los animales y determinar cuales requer\u00edan suplementaci\u00f3n estrat\u00e9gica. Asimismo, recorrieron <strong>potreros silvopastoriles<\/strong> para evaluar a simple vista la disponibilidad de forraje  y analizar el comportamiento ingestivo de la majada caprina presente en el establecimiento\u00a0<\/p>\n\n\n\n<p>La jornada estuvo a cargo de la ingeniera agr\u00f3noma <strong>Alicia C\u00f3rdoba<\/strong>, quien acompa\u00f1\u00f3 a los estudiantes durante las actividades pr\u00e1cticas, brindando orientaci\u00f3n t\u00e9cnica y promoviendo el aprendizaje a partir de situaciones reales de producci\u00f3n. Desde la <strong>Facultad de Ciencias de la Salud<\/strong> agradecieron al INTA por brindar el espacio, destacando la importancia de concretar estas instancias de formaci\u00f3n para los futuros profesionales.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos tuvieron la posibilidad de manejar herramientas para evaluar el ganado y recorrieron potreros silvopastoriles.<\/p>\n","protected":false},"author":6,"featured_media":13240,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[9],"tags":[52,132],"_links":{"self":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts\/13239"}],"collection":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/comments?post=13239"}],"version-history":[{"count":3,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts\/13239\/revisions"}],"predecessor-version":[{"id":13251,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts\/13239\/revisions\/13251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/media\/13240"}],"wp:attachment":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/media?parent=13239"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/categories?post=13239"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/tags?post=13239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}