{"id":686,"date":"2014-05-25T15:43:12","date_gmt":"2014-05-25T15:43:12","guid":{"rendered":"http:\/\/www.ucse.edu.ar\/notiucse\/?p=686"},"modified":"2014-06-06T15:49:47","modified_gmt":"2014-06-06T15:49:47","slug":"juegos-didacticos-en-la-facultad-de-matematica-aplicada-de-la-sede-central","status":"publish","type":"post","link":"https:\/\/www.ucse.edu.ar\/notiucse\/2014\/05\/25\/juegos-didacticos-en-la-facultad-de-matematica-aplicada-de-la-sede-central\/","title":{"rendered":"Juegos Did\u00e1cticos en la Facultad de Matem\u00e1tica Aplicada de la Sede Central"},"content":{"rendered":"<p>El mi\u00e9rcoles 7 de mayo del corriente se realiz\u00f3 una experiencia pedag\u00f3gica en la Asignatura Sistemas de Informaci\u00f3n II de la carrera Ing. en Inform\u00e1tica, basada en juegos para fortalecer el proceso ense\u00f1anza \u2013 aprendizaje.<\/p>\n<p>Se introdujo a los alumnos\u00a0 en la tem\u00e1tica de Metodolog\u00edas \u00c1giles para el Desarrollo de Software, utilizando como recurso did\u00e1ctico la simulaci\u00f3n con piezas de LEGOS.<\/p>\n<p>Esta pr\u00e1ctica favoreci\u00f3 la participaci\u00f3n del estudiante bajo un esquema colaborativo y result\u00f3 muy satisfactoria.<\/p>\n<p><a href=\"http:\/\/www.ucse.edu.ar\/notiucse\/wp-content\/uploads\/2014\/06\/1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-687\" src=\"http:\/\/www.ucse.edu.ar\/notiucse\/wp-content\/uploads\/2014\/06\/1.jpg\" alt=\"1\" width=\"2506\" height=\"1410\" srcset=\"https:\/\/www.ucse.edu.ar\/notiucse\/wp-content\/uploads\/2014\/06\/1.jpg 2506w, https:\/\/www.ucse.edu.ar\/notiucse\/wp-content\/uploads\/2014\/06\/1-300x168.jpg 300w, https:\/\/www.ucse.edu.ar\/notiucse\/wp-content\/uploads\/2014\/06\/1-1024x576.jpg 1024w, https:\/\/www.ucse.edu.ar\/notiucse\/wp-content\/uploads\/2014\/06\/1-460x260.jpg 460w\" sizes=\"(max-width: 2506px) 100vw, 2506px\" \/><\/a> <a href=\"http:\/\/www.ucse.edu.ar\/notiucse\/wp-content\/uploads\/2014\/06\/2.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-688\" src=\"http:\/\/www.ucse.edu.ar\/notiucse\/wp-content\/uploads\/2014\/06\/2.jpg\" alt=\"2\" width=\"2474\" height=\"1394\" srcset=\"https:\/\/www.ucse.edu.ar\/notiucse\/wp-content\/uploads\/2014\/06\/2.jpg 2474w, https:\/\/www.ucse.edu.ar\/notiucse\/wp-content\/uploads\/2014\/06\/2-300x169.jpg 300w, https:\/\/www.ucse.edu.ar\/notiucse\/wp-content\/uploads\/2014\/06\/2-1024x576.jpg 1024w, https:\/\/www.ucse.edu.ar\/notiucse\/wp-content\/uploads\/2014\/06\/2-460x260.jpg 460w\" sizes=\"(max-width: 2474px) 100vw, 2474px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El mi\u00e9rcoles 7 de mayo del corriente se realiz\u00f3 una experiencia pedag\u00f3gica en la Asignatura Sistemas de Informaci\u00f3n II de la carrera Ing. en Inform\u00e1tica, basada en juegos para fortalecer el proceso ense\u00f1anza \u2013 aprendizaje. Se introdujo a los alumnos\u00a0 en la tem\u00e1tica de Metodolog\u00edas \u00c1giles para el Desarrollo de Software, utilizando como recurso did\u00e1ctico [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":687,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[10],"tags":[59,31],"_links":{"self":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts\/686"}],"collection":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/comments?post=686"}],"version-history":[{"count":1,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts\/686\/revisions"}],"predecessor-version":[{"id":689,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/posts\/686\/revisions\/689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/media\/687"}],"wp:attachment":[{"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/media?parent=686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/categories?post=686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ucse.edu.ar\/notiucse\/wp-json\/wp\/v2\/tags?post=686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}